{"id":1171,"date":"2025-08-26T09:03:06","date_gmt":"2025-08-26T09:03:06","guid":{"rendered":"https:\/\/pacificcables.com\/?page_id=1171"},"modified":"2026-01-12T04:14:41","modified_gmt":"2026-01-12T04:14:41","slug":"bare-overhead-conductors","status":"publish","type":"page","link":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/","title":{"rendered":"Bare Overhead Conductors"},"content":{"rendered":"<style>.kb-row-layout-id1171_8fc299-2a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1171_8fc299-2a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1171_8fc299-2a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1140px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1171_8fc299-2a{background-image:url('https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Orange-and-White-Modern-Find-Your-Dream-House-Banner-9-scaled.png');background-size:cover;background-position:2% 100%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id1171_8fc299-2a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1171_8fc299-2a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1171_8fc299-2a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1171_8fc299-2a{background-image:url('https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Orange-and-White-Modern-Find-Your-Dream-House-Banner-9-scaled.png');background-size:cover;background-position:28.000000000000004% 49%;background-attachment:scroll;background-repeat:no-repeat;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1171_8fc299-2a alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{display:flex;}.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);}.kadence-column1171_9af0e3-97 > .kt-inside-inner-col,.kadence-column1171_9af0e3-97 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_9af0e3-97 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1171_9af0e3-97{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_9af0e3-97{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_9af0e3-97 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1171_9af0e3-97{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1171_9af0e3-97{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_9af0e3-97{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1171_9af0e3-97{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_9af0e3-97{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_9af0e3-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_9af0e3-97\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group is-layout-grid wp-container-core-group-is-layout-8d2db683 wp-block-group-is-layout-grid\"><style>.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{display:flex;}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{box-shadow:0px 0px 0px 0px rgba(0, 0, 0, 0.2);}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col,.kadence-column1171_7ffba8-54 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1171_7ffba8-54{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ffba8-54{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col:before{opacity:0.7;}.kadence-column1171_7ffba8-54{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1171_7ffba8-54{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ffba8-54{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1171_7ffba8-54{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ffba8-54{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_7ffba8-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_7ffba8-54\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1171_5728c4-97, .wp-block-kadence-advancedheading.kt-adv-heading1171_5728c4-97[data-kb-block=\"kb-adv-heading1171_5728c4-97\"]{padding-bottom:var(--global-kb-spacing-lg, 3rem);font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1171_5728c4-97 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1171_5728c4-97[data-kb-block=\"kb-adv-heading1171_5728c4-97\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1171_5728c4-97 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1171_5728c4-97[data-kb-block=\"kb-adv-heading1171_5728c4-97\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading1171_5728c4-97 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1171_5728c4-97\">Our Products<\/h1>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1171_bbfa27-39, .wp-block-kadence-advancedheading.kt-adv-heading1171_bbfa27-39[data-kb-block=\"kb-adv-heading1171_bbfa27-39\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1171_bbfa27-39 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1171_bbfa27-39[data-kb-block=\"kb-adv-heading1171_bbfa27-39\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1171_bbfa27-39 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1171_bbfa27-39[data-kb-block=\"kb-adv-heading1171_bbfa27-39\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1171_bbfa27-39 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1171_bbfa27-39\">Bare Overhead Conductors<\/h2>\n\n\n<style>.kb-row-layout-id1171_44f599-21 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1171_44f599-21 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1171_44f599-21 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1171_44f599-21 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1171_44f599-21 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1171_44f599-21 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1171_44f599-21 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1171_28dcf0-10 > .kt-inside-inner-col,.kadence-column1171_28dcf0-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_28dcf0-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_28dcf0-10 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1171_28dcf0-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1171_28dcf0-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1171_28dcf0-10{position:relative;}@media all and (max-width: 1024px){.kadence-column1171_28dcf0-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1171_28dcf0-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_28dcf0-10\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1171_d2c801-65, .wp-block-kadence-advancedheading.kt-adv-heading1171_d2c801-65[data-kb-block=\"kb-adv-heading1171_d2c801-65\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1171_d2c801-65 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1171_d2c801-65[data-kb-block=\"kb-adv-heading1171_d2c801-65\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1171_d2c801-65 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1171_d2c801-65[data-kb-block=\"kb-adv-heading1171_d2c801-65\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1171_d2c801-65 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1171_d2c801-65\">Get complete details about our high-quality Bare Overhead Conductors, including specifications, features, and applications. Download the catalog to explore reliable solutions designed for durability, safety, and performance.<br><a href=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/pvc1.pdf\"><\/a><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{display:flex;}.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col,.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1171_ef3a0a-2c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_ef3a0a-2c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1171_ef3a0a-2c{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1171_ef3a0a-2c{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_ef3a0a-2c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1171_ef3a0a-2c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_ef3a0a-2c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_ef3a0a-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_ef3a0a-2c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1171_bc2984-6e{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns1171_bc2984-6e .kt-button{font-weight:normal;font-style:normal;}.kt-btns1171_bc2984-6e .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1171_bc2984-6e .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1171_bc2984-6e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1171_bc2984-6e .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1171_bc2984-6e .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1171_bc2984-6e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1171_bc2984-6e .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1171_bc2984-6e\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1171_2a91b5-a3.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1171_2a91b5-a3.kb-button{background:var(--global-palette3, #1A202C);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-md, 2rem);}.wp-block-kadence-advancedbtn .kb-btn1171_2a91b5-a3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1171_2a91b5-a3.kb-button:focus{color:var(--global-palette8, #F7FAFC);background:#f7261e;}<\/style><a class=\"kb-button kt-button button kb-btn1171_2a91b5-a3 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/bare-overhead-Conductors.pdf\"><span class=\"kt-btn-inner-text\">Download<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1171_c1f535-c7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1171_c1f535-c7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1171_c1f535-c7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1171_a2de43-7b > .kt-inside-inner-col{display:flex;}.kadence-column1171_a2de43-7b > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1171_a2de43-7b > .kt-inside-inner-col,.kadence-column1171_a2de43-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_a2de43-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_a2de43-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_a2de43-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1171_a2de43-7b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_a2de43-7b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_a2de43-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_a2de43-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1171_a2de43-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column1171_a2de43-7b > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1171_a2de43-7b{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_a2de43-7b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_a2de43-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1171_a2de43-7b > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1171_a2de43-7b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_a2de43-7b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_a2de43-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_a2de43-7b kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"251\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210.png\" alt=\"\" class=\"wp-image-1454\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210-300x233.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1171_4fbffe-27, .wp-block-kadence-advancedheading.kt-adv-heading1171_4fbffe-27[data-kb-block=\"kb-adv-heading1171_4fbffe-27\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1171_4fbffe-27 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1171_4fbffe-27[data-kb-block=\"kb-adv-heading1171_4fbffe-27\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1171_4fbffe-27 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1171_4fbffe-27[data-kb-block=\"kb-adv-heading1171_4fbffe-27\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1171_4fbffe-27 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1171_4fbffe-27\">AAC 1350 &#8211; ALL Aluminium Conductors<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/28\/aac-1350-all-aluminium-conductors\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{display:flex;}.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1171_7ef722-b4 > .kt-inside-inner-col,.kadence-column1171_7ef722-b4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_7ef722-b4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1171_7ef722-b4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ef722-b4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_7ef722-b4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1171_7ef722-b4{position:relative;}@media all and (max-width: 1024px){.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1171_7ef722-b4{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ef722-b4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1171_7ef722-b4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ef722-b4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_7ef722-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_7ef722-b4 kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"251\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q208.png\" alt=\"\" class=\"wp-image-1455\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q208.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q208-300x233.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1171_d49010-89, .wp-block-kadence-advancedheading.kt-adv-heading1171_d49010-89[data-kb-block=\"kb-adv-heading1171_d49010-89\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1171_d49010-89 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1171_d49010-89[data-kb-block=\"kb-adv-heading1171_d49010-89\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1171_d49010-89 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1171_d49010-89[data-kb-block=\"kb-adv-heading1171_d49010-89\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1171_d49010-89 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1171_d49010-89\">AAAC 1120 &#8211; ALL Aluminium Alloy Conductors<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/28\/aaac-1120-all-aluminium-alloy-conductors\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{display:flex;}.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1171_e338fe-c2 > .kt-inside-inner-col,.kadence-column1171_e338fe-c2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_e338fe-c2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1171_e338fe-c2{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_e338fe-c2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1171_e338fe-c2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1171_e338fe-c2{position:relative;}@media all and (max-width: 1024px){.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1171_e338fe-c2{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_e338fe-c2{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1171_e338fe-c2{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_e338fe-c2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1171_e338fe-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_e338fe-c2 kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"250\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q209.png\" alt=\"\" class=\"wp-image-1456\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q209.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q209-300x232.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1171_fb67cf-dc, .wp-block-kadence-advancedheading.kt-adv-heading1171_fb67cf-dc[data-kb-block=\"kb-adv-heading1171_fb67cf-dc\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1171_fb67cf-dc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1171_fb67cf-dc[data-kb-block=\"kb-adv-heading1171_fb67cf-dc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1171_fb67cf-dc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1171_fb67cf-dc[data-kb-block=\"kb-adv-heading1171_fb67cf-dc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1171_fb67cf-dc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1171_fb67cf-dc\">ACSR &#8211; Aluminium Conductors Steel Reinforced<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/28\/acsr-aluminium-conductors-steel-reinforced\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col,.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1171_1e2ba2-94{position:relative;}@media all and (max-width: 1024px){.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1171_1e2ba2-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1171_1e2ba2-94\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Our Products Bare Overhead Conductors Get complete details about our high-quality Bare Overhead Conductors, including specifications, features, and applications. Download the catalog to explore reliable solutions designed for durability, safety, and performance. AAC 1350 &#8211; ALL Aluminium Conductors AAAC 1120 &#8211; ALL Aluminium Alloy Conductors ACSR &#8211; Aluminium Conductors Steel Reinforced<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-1171","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bare Overhead Conductors | Pacific Cable<\/title>\n<meta name=\"description\" content=\"High-quality bare overhead conductors designed for efficient and reliable power transmission. Built for durability in tropical and demanding environments.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bare Overhead Conductors | Pacific Cable\" \/>\n<meta property=\"og:description\" content=\"High-quality bare overhead conductors designed for efficient and reliable power transmission. Built for durability in tropical and demanding environments.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/\" \/>\n<meta property=\"og:site_name\" content=\"Pacific Cable\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Pacific-Cables-100069947232941\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T04:14:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210.png\" \/>\n\t<meta property=\"og:image:width\" content=\"323\" \/>\n\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/\",\"name\":\"Bare Overhead Conductors | Pacific Cable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Group-q210.png\",\"datePublished\":\"2025-08-26T09:03:06+00:00\",\"dateModified\":\"2026-01-12T04:14:41+00:00\",\"description\":\"High-quality bare overhead conductors designed for efficient and reliable power transmission. Built for durability in tropical and demanding environments.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Group-q210.png\",\"contentUrl\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Group-q210.png\",\"width\":323,\"height\":251},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/bare-overhead-conductors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pacificcables.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bare Overhead Conductors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#website\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/\",\"name\":\"Pacific Cables\",\"description\":\"The Safe Choice For a Sustainable Future\",\"publisher\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#organization\"},\"alternateName\":\"Pacific Cables\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pacificcables.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#organization\",\"name\":\"Pacific Cables\",\"alternateName\":\"Pacific Cables\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/image-removebg-preview-18-2.png\",\"contentUrl\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/image-removebg-preview-18-2.png\",\"width\":150,\"height\":65,\"caption\":\"Pacific Cables\"},\"image\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Pacific-Cables-100069947232941\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bare Overhead Conductors | Pacific Cable","description":"High-quality bare overhead conductors designed for efficient and reliable power transmission. Built for durability in tropical and demanding environments.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/","og_locale":"en_US","og_type":"article","og_title":"Bare Overhead Conductors | Pacific Cable","og_description":"High-quality bare overhead conductors designed for efficient and reliable power transmission. Built for durability in tropical and demanding environments.","og_url":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/","og_site_name":"Pacific Cable","article_publisher":"https:\/\/www.facebook.com\/p\/Pacific-Cables-100069947232941\/","article_modified_time":"2026-01-12T04:14:41+00:00","og_image":[{"width":323,"height":251,"url":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/","url":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/","name":"Bare Overhead Conductors | Pacific Cable","isPartOf":{"@id":"https:\/\/pacificcables.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/#primaryimage"},"image":{"@id":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/#primaryimage"},"thumbnailUrl":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210.png","datePublished":"2025-08-26T09:03:06+00:00","dateModified":"2026-01-12T04:14:41+00:00","description":"High-quality bare overhead conductors designed for efficient and reliable power transmission. Built for durability in tropical and demanding environments.","breadcrumb":{"@id":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/#primaryimage","url":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210.png","contentUrl":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-q210.png","width":323,"height":251},{"@type":"BreadcrumbList","@id":"https:\/\/pacificcables.com\/index.php\/bare-overhead-conductors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pacificcables.com\/"},{"@type":"ListItem","position":2,"name":"Bare Overhead Conductors"}]},{"@type":"WebSite","@id":"https:\/\/pacificcables.com\/#website","url":"https:\/\/pacificcables.com\/","name":"Pacific Cables","description":"The Safe Choice For a Sustainable Future","publisher":{"@id":"https:\/\/pacificcables.com\/#organization"},"alternateName":"Pacific Cables","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pacificcables.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pacificcables.com\/#organization","name":"Pacific Cables","alternateName":"Pacific Cables","url":"https:\/\/pacificcables.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pacificcables.com\/#\/schema\/logo\/image\/","url":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/image-removebg-preview-18-2.png","contentUrl":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/image-removebg-preview-18-2.png","width":150,"height":65,"caption":"Pacific Cables"},"image":{"@id":"https:\/\/pacificcables.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Pacific-Cables-100069947232941\/"]}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages\/1171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/comments?post=1171"}],"version-history":[{"count":5,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages\/1171\/revisions"}],"predecessor-version":[{"id":1755,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages\/1171\/revisions\/1755"}],"wp:attachment":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/media?parent=1171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}