{"id":1161,"date":"2025-08-26T08:59:33","date_gmt":"2025-08-26T08:59:33","guid":{"rendered":"https:\/\/pacificcables.com\/?page_id=1161"},"modified":"2026-01-12T09:04:09","modified_gmt":"2026-01-12T09:04:09","slug":"flexible-cables","status":"publish","type":"page","link":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/","title":{"rendered":"Flexible Cables"},"content":{"rendered":"<style>.kb-row-layout-id1161_61de75-ca > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1161_61de75-ca > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1161_61de75-ca > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1140px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1161_61de75-ca{background-image:url('https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Orange-and-White-Modern-Find-Your-Dream-House-Banner-9-scaled.png');background-size:cover;background-position:2% 100%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id1161_61de75-ca > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1161_61de75-ca > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1161_61de75-ca > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1161_61de75-ca{background-image:url('https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Orange-and-White-Modern-Find-Your-Dream-House-Banner-9-scaled.png');background-size:cover;background-position:28.000000000000004% 49%;background-attachment:scroll;background-repeat:no-repeat;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1161_61de75-ca alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{display:flex;}.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);}.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col,.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_4a4b4a-bd{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_4a4b4a-bd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_4a4b4a-bd{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_4a4b4a-bd{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_4a4b4a-bd{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1161_4a4b4a-bd{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_4a4b4a-bd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_4a4b4a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_4a4b4a-bd\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group is-layout-grid wp-container-core-group-is-layout-8d2db683 wp-block-group-is-layout-grid\"><style>.kadence-column1161_cb857b-12 > .kt-inside-inner-col{display:flex;}.kadence-column1161_cb857b-12 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);}.kadence-column1161_cb857b-12 > .kt-inside-inner-col{box-shadow:0px 0px 0px 0px rgba(0, 0, 0, 0.2);}.kadence-column1161_cb857b-12 > .kt-inside-inner-col,.kadence-column1161_cb857b-12 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_cb857b-12 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_cb857b-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_cb857b-12 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_cb857b-12{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cb857b-12{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cb857b-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_cb857b-12 > .kt-inside-inner-col:before{opacity:0.7;}.kadence-column1161_cb857b-12{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_cb857b-12{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cb857b-12{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cb857b-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1161_cb857b-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1161_cb857b-12{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cb857b-12{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cb857b-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_cb857b-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_cb857b-12\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1161_06b81d-b8, .wp-block-kadence-advancedheading.kt-adv-heading1161_06b81d-b8[data-kb-block=\"kb-adv-heading1161_06b81d-b8\"]{padding-bottom:var(--global-kb-spacing-lg, 3rem);font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_06b81d-b8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_06b81d-b8[data-kb-block=\"kb-adv-heading1161_06b81d-b8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_06b81d-b8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_06b81d-b8[data-kb-block=\"kb-adv-heading1161_06b81d-b8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading1161_06b81d-b8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_06b81d-b8\">Our Products<\/h1>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1161_3a48b9-44, .wp-block-kadence-advancedheading.kt-adv-heading1161_3a48b9-44[data-kb-block=\"kb-adv-heading1161_3a48b9-44\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_3a48b9-44 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_3a48b9-44[data-kb-block=\"kb-adv-heading1161_3a48b9-44\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_3a48b9-44 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_3a48b9-44[data-kb-block=\"kb-adv-heading1161_3a48b9-44\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1161_3a48b9-44 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_3a48b9-44\">Flexible Cables<\/h2>\n\n\n<style>.kb-row-layout-id1161_6a76ac-50 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1161_6a76ac-50 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1161_6a76ac-50 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1161_6a76ac-50 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1161_6a76ac-50 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1161_6a76ac-50 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1161_6a76ac-50 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1161_029e18-8a > .kt-inside-inner-col,.kadence-column1161_029e18-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_029e18-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_029e18-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1161_029e18-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1161_029e18-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_029e18-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column1161_029e18-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1161_029e18-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_029e18-8a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1161_3313b1-e9, .wp-block-kadence-advancedheading.kt-adv-heading1161_3313b1-e9[data-kb-block=\"kb-adv-heading1161_3313b1-e9\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_3313b1-e9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_3313b1-e9[data-kb-block=\"kb-adv-heading1161_3313b1-e9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_3313b1-e9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_3313b1-e9[data-kb-block=\"kb-adv-heading1161_3313b1-e9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1161_3313b1-e9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_3313b1-e9\">Get complete details about our high-quality Flexible Cables, including specifications, features, and applications. Download the catalog to explore reliable solutions designed for durability, safety, and performance.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1161_fd090c-0d > .kt-inside-inner-col{display:flex;}.kadence-column1161_fd090c-0d > .kt-inside-inner-col,.kadence-column1161_fd090c-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_fd090c-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_fd090c-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_fd090c-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_fd090c-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fd090c-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fd090c-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_fd090c-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_fd090c-0d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_fd090c-0d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fd090c-0d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fd090c-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1161_fd090c-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1161_fd090c-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fd090c-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fd090c-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_fd090c-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_fd090c-0d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1161_9ae080-85{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns1161_9ae080-85 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1161_9ae080-85 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1161_9ae080-85 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1161_9ae080-85 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1161_9ae080-85 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1161_9ae080-85 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1161_9ae080-85 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1161_9ae080-85 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1161_9ae080-85\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1161_81e672-14.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1161_81e672-14.kb-button{background:var(--global-palette3, #1A202C);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-md, 2rem);}.wp-block-kadence-advancedbtn .kb-btn1161_81e672-14.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1161_81e672-14.kb-button:focus{color:var(--global-palette8, #F7FAFC);background:#f7261e;}<\/style><a class=\"kb-button kt-button button kb-btn1161_81e672-14 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/FlexibleCable.pdf\"><span class=\"kt-btn-inner-text\">Download<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1161_fbe94d-9b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1161_fbe94d-9b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1161_fbe94d-9b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1161_631fda-41 > .kt-inside-inner-col{display:flex;}.kadence-column1161_631fda-41 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1161_631fda-41 > .kt-inside-inner-col,.kadence-column1161_631fda-41 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_631fda-41 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_631fda-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_631fda-41 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_631fda-41{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_631fda-41{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_631fda-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_631fda-41 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_631fda-41{position:relative;}@media all and (max-width: 1024px){.kadence-column1161_631fda-41 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_631fda-41{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_631fda-41{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_631fda-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1161_631fda-41 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1161_631fda-41{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_631fda-41{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_631fda-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_631fda-41 kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"250\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194.png\" alt=\"\" class=\"wp-image-1330\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194-300x232.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1161_8843da-e8, .wp-block-kadence-advancedheading.kt-adv-heading1161_8843da-e8[data-kb-block=\"kb-adv-heading1161_8843da-e8\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_8843da-e8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_8843da-e8[data-kb-block=\"kb-adv-heading1161_8843da-e8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_8843da-e8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_8843da-e8[data-kb-block=\"kb-adv-heading1161_8843da-e8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1161_8843da-e8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_8843da-e8\">Flexible Cord PVC TRURIP (Twin Flex)<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/27\/flexible-cord-pvc-trurip-twin-flex\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{display:flex;}.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col,.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_7e97e0-b3{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_7e97e0-b3{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_7e97e0-b3{position:relative;}@media all and (max-width: 1024px){.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_7e97e0-b3{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_7e97e0-b3{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1161_7e97e0-b3{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_7e97e0-b3{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_7e97e0-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_7e97e0-b3 kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"250\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-195.png\" alt=\"\" class=\"wp-image-1331\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-195.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-195-300x232.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1161_0ef4aa-37, .wp-block-kadence-advancedheading.kt-adv-heading1161_0ef4aa-37[data-kb-block=\"kb-adv-heading1161_0ef4aa-37\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_0ef4aa-37 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_0ef4aa-37[data-kb-block=\"kb-adv-heading1161_0ef4aa-37\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_0ef4aa-37 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_0ef4aa-37[data-kb-block=\"kb-adv-heading1161_0ef4aa-37\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1161_0ef4aa-37 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_0ef4aa-37\">Flex Ordinary Duty 2C<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/27\/flex-ordinary-duty-2c\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{display:flex;}.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col,.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_fc4e0c-4a{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fc4e0c-4a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_fc4e0c-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_fc4e0c-4a{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fc4e0c-4a{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1161_fc4e0c-4a{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fc4e0c-4a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_fc4e0c-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_fc4e0c-4a kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"251\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-196.png\" alt=\"\" class=\"wp-image-1332\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-196.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-196-300x233.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1161_7e19f6-2e, .wp-block-kadence-advancedheading.kt-adv-heading1161_7e19f6-2e[data-kb-block=\"kb-adv-heading1161_7e19f6-2e\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_7e19f6-2e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_7e19f6-2e[data-kb-block=\"kb-adv-heading1161_7e19f6-2e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_7e19f6-2e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_7e19f6-2e[data-kb-block=\"kb-adv-heading1161_7e19f6-2e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1161_7e19f6-2e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_7e19f6-2e\">Flex Ordinary Duty 3C<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/27\/flex-ordinary-duty-3c\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1161_cd0200-83 > .kt-inside-inner-col{display:flex;}.kadence-column1161_cd0200-83 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1161_cd0200-83 > .kt-inside-inner-col,.kadence-column1161_cd0200-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_cd0200-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_cd0200-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_cd0200-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_cd0200-83{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cd0200-83{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cd0200-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_cd0200-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_cd0200-83{position:relative;}@media all and (max-width: 1024px){.kadence-column1161_cd0200-83 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_cd0200-83{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cd0200-83{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cd0200-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1161_cd0200-83 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1161_cd0200-83{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cd0200-83{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_cd0200-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_cd0200-83 kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"251\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-197.png\" alt=\"\" class=\"wp-image-1333\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-197.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-197-300x233.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1161_cb4202-1a, .wp-block-kadence-advancedheading.kt-adv-heading1161_cb4202-1a[data-kb-block=\"kb-adv-heading1161_cb4202-1a\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_cb4202-1a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_cb4202-1a[data-kb-block=\"kb-adv-heading1161_cb4202-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_cb4202-1a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_cb4202-1a[data-kb-block=\"kb-adv-heading1161_cb4202-1a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1161_cb4202-1a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_cb4202-1a\">Flex Ordinary Duty 4C<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/27\/flex-ordinary-duty-4c\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{display:flex;}.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1161_b5b231-a6 > .kt-inside-inner-col,.kadence-column1161_b5b231-a6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_b5b231-a6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1161_b5b231-a6{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_b5b231-a6{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1161_b5b231-a6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_b5b231-a6{position:relative;}@media all and (max-width: 1024px){.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1161_b5b231-a6{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_b5b231-a6{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column1161_b5b231-a6{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_b5b231-a6{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1161_b5b231-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_b5b231-a6 kb-section-has-link\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"250\" src=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-198.png\" alt=\"\" class=\"wp-image-1334\" srcset=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-198.png 323w, https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-198-300x232.png 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1161_951b96-42, .wp-block-kadence-advancedheading.kt-adv-heading1161_951b96-42[data-kb-block=\"kb-adv-heading1161_951b96-42\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1161_951b96-42 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1161_951b96-42[data-kb-block=\"kb-adv-heading1161_951b96-42\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1161_951b96-42 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1161_951b96-42[data-kb-block=\"kb-adv-heading1161_951b96-42\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading1161_951b96-42 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1161_951b96-42\">Flex Heavy Duty 3 Core<\/h5>\n<\/div><a href=\"https:\/\/pacificcables.com\/index.php\/2025\/08\/27\/flex-heavy-duty-3-core\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1161_30b891-91 > .kt-inside-inner-col,.kadence-column1161_30b891-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1161_30b891-91 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1161_30b891-91 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1161_30b891-91 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1161_30b891-91 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1161_30b891-91{position:relative;}@media all and (max-width: 1024px){.kadence-column1161_30b891-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1161_30b891-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1161_30b891-91\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Our Products Flexible Cables Get complete details about our high-quality Flexible Cables, including specifications, features, and applications. Download the catalog to explore reliable solutions designed for durability, safety, and performance. Flexible Cord PVC TRURIP (Twin Flex) Flex Ordinary Duty 2C Flex Ordinary Duty 3C Flex Ordinary Duty 4C Flex Heavy Duty 3 Core<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-1161","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flexible Cables | Pacific Cable<\/title>\n<meta name=\"description\" content=\"High-quality flexible cables designed for durability, safety, and easy installation. Ideal for industrial, commercial, and power applications.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pacificcables.com\/index.php\/flexible-cables\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flexible Cables | Pacific Cable\" \/>\n<meta property=\"og:description\" content=\"High-quality flexible cables designed for durability, safety, and easy installation. Ideal for industrial, commercial, and power applications.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pacificcables.com\/index.php\/flexible-cables\/\" \/>\n<meta property=\"og:site_name\" content=\"Pacific Cable\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Pacific-Cables-100069947232941\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T09:04:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194.png\" \/>\n\t<meta property=\"og:image:width\" content=\"323\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/\",\"name\":\"Flexible Cables | Pacific Cable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Group-194.png\",\"datePublished\":\"2025-08-26T08:59:33+00:00\",\"dateModified\":\"2026-01-12T09:04:09+00:00\",\"description\":\"High-quality flexible cables designed for durability, safety, and easy installation. Ideal for industrial, commercial, and power applications.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Group-194.png\",\"contentUrl\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Group-194.png\",\"width\":323,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/index.php\\\/flexible-cables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pacificcables.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flexible Cables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#website\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/\",\"name\":\"Pacific Cables\",\"description\":\"The Safe Choice For a Sustainable Future\",\"publisher\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#organization\"},\"alternateName\":\"Pacific Cables\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pacificcables.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#organization\",\"name\":\"Pacific Cables\",\"alternateName\":\"Pacific Cables\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/image-removebg-preview-18-2.png\",\"contentUrl\":\"https:\\\/\\\/pacificcables.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/image-removebg-preview-18-2.png\",\"width\":150,\"height\":65,\"caption\":\"Pacific Cables\"},\"image\":{\"@id\":\"https:\\\/\\\/pacificcables.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Pacific-Cables-100069947232941\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flexible Cables | Pacific Cable","description":"High-quality flexible cables designed for durability, safety, and easy installation. Ideal for industrial, commercial, and power applications.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/","og_locale":"en_US","og_type":"article","og_title":"Flexible Cables | Pacific Cable","og_description":"High-quality flexible cables designed for durability, safety, and easy installation. Ideal for industrial, commercial, and power applications.","og_url":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/","og_site_name":"Pacific Cable","article_publisher":"https:\/\/www.facebook.com\/p\/Pacific-Cables-100069947232941\/","article_modified_time":"2026-01-12T09:04:09+00:00","og_image":[{"width":323,"height":250,"url":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/","url":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/","name":"Flexible Cables | Pacific Cable","isPartOf":{"@id":"https:\/\/pacificcables.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/#primaryimage"},"image":{"@id":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/#primaryimage"},"thumbnailUrl":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194.png","datePublished":"2025-08-26T08:59:33+00:00","dateModified":"2026-01-12T09:04:09+00:00","description":"High-quality flexible cables designed for durability, safety, and easy installation. Ideal for industrial, commercial, and power applications.","breadcrumb":{"@id":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pacificcables.com\/index.php\/flexible-cables\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/#primaryimage","url":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194.png","contentUrl":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/Group-194.png","width":323,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/pacificcables.com\/index.php\/flexible-cables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pacificcables.com\/"},{"@type":"ListItem","position":2,"name":"Flexible Cables"}]},{"@type":"WebSite","@id":"https:\/\/pacificcables.com\/#website","url":"https:\/\/pacificcables.com\/","name":"Pacific Cables","description":"The Safe Choice For a Sustainable Future","publisher":{"@id":"https:\/\/pacificcables.com\/#organization"},"alternateName":"Pacific Cables","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pacificcables.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pacificcables.com\/#organization","name":"Pacific Cables","alternateName":"Pacific Cables","url":"https:\/\/pacificcables.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pacificcables.com\/#\/schema\/logo\/image\/","url":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/image-removebg-preview-18-2.png","contentUrl":"https:\/\/pacificcables.com\/wp-content\/uploads\/2025\/08\/image-removebg-preview-18-2.png","width":150,"height":65,"caption":"Pacific Cables"},"image":{"@id":"https:\/\/pacificcables.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Pacific-Cables-100069947232941\/"]}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages\/1161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/comments?post=1161"}],"version-history":[{"count":7,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages\/1161\/revisions"}],"predecessor-version":[{"id":1738,"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/pages\/1161\/revisions\/1738"}],"wp:attachment":[{"href":"https:\/\/pacificcables.com\/index.php\/wp-json\/wp\/v2\/media?parent=1161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}